{"id":2282,"date":"2025-06-19T01:53:36","date_gmt":"2025-06-19T01:53:36","guid":{"rendered":"https:\/\/fleidvn.com\/contact\/"},"modified":"2026-08-05T02:13:17","modified_gmt":"2026-08-05T02:13:17","slug":"contact","status":"publish","type":"page","link":"https:\/\/www.fleidvn.com\/en\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\n  <div class=\"banner has-hover\" id=\"banner-1122267634\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1672\" height=\"941\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/05\/bg-lienhe.png\" class=\"bg attachment-original size-original\" alt=\"Bg Contact\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-181288287\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h1 class=\"uppercase\">CONTACT<\/h1>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-181288287 {\n  width: 60%;\n}\n#text-box-181288287 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1122267634 {\n  padding-top: 56.25%;\n}\n#banner-1122267634 .overlay {\n  background-color: rgba(0,0,0,.5);\n}\n@media (min-width:550px) {\n  #banner-1122267634 {\n    padding-top: 500px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t<section class=\"section\" id=\"section_1604761425\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\t<div id=\"text-388171371\" class=\"text\">\n\t\t\n<h2 class=\"uppercase\">\nContact Us<\/h2>\n\t\t\n<style>\n#text-388171371 {\n  font-size: 1.2rem;\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-388171371 > * {\n  color: rgb(0,0,0);\n}\n@media (min-width:550px) {\n  #text-388171371 {\n    font-size: 1.6rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-2135248961\">\n\n\t<div id=\"col-1971712361\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f2291-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"2291\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/2282#wpcf7-f2291-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"2291\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2291-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"contact-form\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full Name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-address\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Address\" value=\"\" type=\"text\" name=\"your-address\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone Number\" value=\"\" type=\"tel\" name=\"your-phone\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Message\" name=\"your-message\"><\/textarea><\/span>\n\t<\/p>\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send Information\" \/>\n\t<\/p>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"226\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-683632531\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1606288930\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/plastic-bottles-table-2048x1365.jpg\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"Plastic Bottles Table\" srcset=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/plastic-bottles-table-2048x1365.jpg 2048w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/plastic-bottles-table-600x400.jpg 600w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/plastic-bottles-table-1200x800.jpg 1200w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/plastic-bottles-table-768x512.jpg 768w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/plastic-bottles-table-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1606288930 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1604761425 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2282","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.fleidvn.com\/en\/wp-json\/wp\/v2\/pages\/2282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fleidvn.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fleidvn.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fleidvn.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fleidvn.com\/en\/wp-json\/wp\/v2\/comments?post=2282"}],"version-history":[{"count":3,"href":"https:\/\/www.fleidvn.com\/en\/wp-json\/wp\/v2\/pages\/2282\/revisions"}],"predecessor-version":[{"id":2286,"href":"https:\/\/www.fleidvn.com\/en\/wp-json\/wp\/v2\/pages\/2282\/revisions\/2286"}],"wp:attachment":[{"href":"https:\/\/www.fleidvn.com\/en\/wp-json\/wp\/v2\/media?parent=2282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}