{"id":2265,"date":"2025-06-30T02:52:06","date_gmt":"2025-06-30T02:52:06","guid":{"rendered":"https:\/\/fleidvn.com\/about-us\/"},"modified":"2026-08-05T01:57:57","modified_gmt":"2026-08-05T01:57:57","slug":"about-us","status":"publish","type":"page","link":"https:\/\/www.fleidvn.com\/en\/about-us\/","title":{"rendered":"About Us"},"content":{"rendered":"\n  <div class=\"banner has-hover\" id=\"banner-1779709416\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/132932.jpg\" class=\"bg attachment-original size-original\" alt=\"132932\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-889041169\" class=\"text-box banner-layer x50 md-x5 lg-x5 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text box-shadow-3\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-2108001701\" class=\"text hide-for-small\">\n\t\t\n<h1 class=\"uppercase\"><strong>FLEID VIETNAM BLOW MOLDING PRODUCTS COMPANY LIMITED<\/strong><\/h1>\n\t\t\n<style>\n#text-2108001701 {\n  font-size: 0.75rem;\n  text-align: center;\n  color: #0071ff;\n}\n#text-2108001701 > * {\n  color: #0071ff;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2037567120\" class=\"text show-for-small\">\n\t\t\n<h2 class=\"uppercase\" style=\"font-size:25px;\"><strong>Hoa Phat Furniture<\/strong><\/h2>\n\t\t\n<style>\n#text-2037567120 {\n  font-size: 0.75rem;\n  color: rgb(114, 87, 64);\n}\n#text-2037567120 > * {\n  color: rgb(114, 87, 64);\n}\n@media (min-width:550px) {\n  #text-2037567120 {\n    font-size: 0.75rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3975712591\" class=\"text\">\n\t\t\n<p>First and foremost, FLEID VIETNAM BLOW MOLDING PRODUCT COMPANY LIMITED would like to express our sincere gratitude to the customers who have been and are currently partnering with us.<\/p>\n\t\t\n<style>\n#text-3975712591 {\n  font-size: 1rem;\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-3975712591 > * {\n  color: rgb(0,0,0);\n}\n@media (min-width:550px) {\n  #text-3975712591 {\n    font-size: 1rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/fleidvn.com\/lien-he\/\" class=\"button secondary is-outline\" target=\"_blank\" rel=\"noopener\">\n\t\t<span>contact now<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-889041169 .text-box-content {\n  background-color: rgb(255, 255, 255);\n  border-radius: 16px;\n  font-size: 96%;\n}\n#text-box-889041169 .text-inner {\n  padding: 20px 20px 20px 20px;\n}\n#text-box-889041169 {\n  width: 89%;\n}\n@media (min-width:550px) {\n  #text-box-889041169 .text-inner {\n    padding: 30px 30px 30px 30px;\n  }\n  #text-box-889041169 {\n    width: 65%;\n  }\n  #text-box-889041169 .text-box-content {\n    font-size: 100%;\n  }\n}\n@media (min-width:850px) {\n  #text-box-889041169 {\n    width: 100%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1779709416 {\n  padding-top: 500px;\n}\n#banner-1779709416 .overlay {\n  background-color: rgba(255,255,255,.5);\n}\n@media (min-width:550px) {\n  #banner-1779709416 {\n    padding-top: 600px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t<section class=\"section\" id=\"section_1802371803\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<span class=\"scroll-to\" data-label=\"Scroll to: #gioithieu\" data-bullet=\"false\" data-link=\"#gioithieu\" data-title=\"Change this\" ><a name=\"gioithieu\"><\/a><\/span>\n<div class=\"row align-middle align-center\"  id=\"row-1759873461\">\n\n\t<div id=\"col-458961645\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1306877334\" class=\"text hide-for-small\">\n\t\t\n<h2 class=\"uppercase\"><strong>WE ARE A RELIABLE PACKAGING SERVICE PARTNER, PROVIDING ALL-IN-ONE PLASTIC PACKAGING SERVICES.<\/strong><\/h2>\n\t\t\n<style>\n#text-1306877334 {\n  font-size: 1rem;\n  text-align: left;\n  color: #0071ff;\n}\n#text-1306877334 > * {\n  color: #0071ff;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3732353046\" class=\"text\">\n\t\t\n<p data-start=\"99\" data-end=\"664\">FLEID Vietnam Blow Molding Product Co., Ltd. specializes in designing and manufacturing a wide range of plastic packaging products. Our production lines can process various materials, and our products are widely used in the food and beverage, pharmaceutical, cosmetic, FMCG, and automotive industries. Our products are also utilized in many other sectors such as toys, lighting, Christmas decorations, stationery, toolboxes, trays, sports water bottles, etc., providing diverse and high-quality plastic packaging solutions.  <\/p>\n<p data-start=\"666\" data-end=\"872\" data-is-last-node=\"\" data-is-only-node=\"\">With modern equipment and advanced production lines, we ensure high quality at reasonable prices. If you are looking for a reliable manufacturing partner, we are the right choice! <\/p>\n\t\t\n<style>\n#text-3732353046 {\n  font-size: 1.1rem;\n  text-align: left;\n  color: rgb(0,0,0);\n}\n#text-3732353046 > * {\n  color: rgb(0,0,0);\n}\n@media (min-width:550px) {\n  #text-3732353046 {\n    font-size: 1.4rem;\n  }\n}\n@media (min-width:850px) {\n  #text-3732353046 {\n    font-size: 1.1rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-458961645 > .col-inner {\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-726479428\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1157492179\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/binh-dung-dung-dich-hao-chat-800x800.jpg\" class=\"attachment-large size-large\" alt=\"Chemical Solution Bottles\" srcset=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/binh-dung-dung-dich-hao-chat-800x800.jpg 800w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/binh-dung-dung-dich-hao-chat-600x600.jpg 600w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/binh-dung-dung-dich-hao-chat-100x100.jpg 100w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/binh-dung-dung-dich-hao-chat-400x400.jpg 400w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/binh-dung-dung-dich-hao-chat-280x280.jpg 280w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/binh-dung-dung-dich-hao-chat-768x768.jpg 768w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/binh-dung-dung-dich-hao-chat.jpg 852w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1157492179 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-726479428 > .col-inner {\n  margin: 10px 0px -40px 0px;\n}\n@media (min-width:850px) {\n  #col-726479428 > .col-inner {\n    margin: 0px 0px -40px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1802371803 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_921531531\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-183500858\">\n\n\t<div id=\"col-656148430\" class=\"col w-100 medium-12 small-12 large-12\"  data-animate=\"fadeInLeft\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p class=\"text-box-icon\" style=\"width: 250px;\"><i class=\"fas fa-circle\" style=\"font-size: 8px; color: #e7ae5c;\"><\/i> WHY CHOOSE US<\/p>\n\t<div id=\"text-1285643717\" class=\"text why-choose-heading\">\n\t\t\n<h2>Reasons Why You Should Choose <span style=\"color: #0071ff;\">Us<\/span><\/h2>\n\t\t\n<style>\n#text-1285643717 {\n  font-size: 1.5rem;\n}\n@media (min-width:550px) {\n  #text-1285643717 {\n    font-size: 1.5rem;\n  }\n}\n@media (min-width:850px) {\n  #text-1285643717 {\n    font-size: 1.5rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-785911610\" class=\"text\">\n\t\t\n<p>We do not only provide HDPE plastic bottle products that meet quality standards but also always accompany our customers with dedication and prestige. Every product created is a commitment to durability, stability, and meticulous care in every production stage. <\/p>\n\t\t\n<style>\n#text-785911610 {\n  color: rgb(40, 49, 50);\n}\n#text-785911610 > * {\n  color: rgb(40, 49, 50);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-center\"  id=\"row-817443527\">\n\n\t<div id=\"col-27712332\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-why icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 46px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/06\/best-customer-experience-100x100-1.png\" class=\"attachment-medium size-medium\" alt=\"Best Customer Experience 100x100 (1)\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"text-621565620\" class=\"text\">\n\t\t\n<h3>Rich Experience<\/h3>\n<p>Our predecessor was one of the leading manufacturers of flexible packaging materials in Dongguan, Guangdong, China, with over 20 years of experience. We have extensive experience and have prevented many issues during the production process; only quality-assured products are delivered to customers.<br \/>\n\t\t\n<style>\n#text-621565620 {\n  color: rgb(40, 49, 50);\n}\n#text-621565620 > * {\n  color: rgb(40, 49, 50);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1077843276\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-why icon-box-left text-left\"  style=\"margin:10px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 46px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/06\/commitment-100x100-1.png\" class=\"attachment-medium size-medium\" alt=\"Commitment 100x100 (1)\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"text-1879513526\" class=\"text\">\n\t\t\n<h3>Leading Equipment<\/h3>\n<p>Our machinery system is suitable for producing various lines of plastic bottles with diverse designs, capacities, and weights. Production molds are precisely processed to the millimeter, helping products achieve high uniformity and aesthetics. We focus on using high-quality HDPE materials, ensuring durability, safety, and optimization for packaging needs.  <\/p>\n\t\t\n<style>\n#text-1879513526 {\n  color: rgb(40, 49, 50);\n}\n#text-1879513526 > * {\n  color: rgb(40, 49, 50);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1425461749\">\n\n\t<div id=\"col-1911796332\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-why icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 46px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/06\/best-customer-experience-100x100-1.png\" class=\"attachment-medium size-medium\" alt=\"Best Customer Experience 100x100 (1)\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"text-663726236\" class=\"text\">\n\t\t\n<h3>On-time Delivery<\/h3>\n<p>We are a direct manufacturer. All processes are controlled, ensuring we can operate production and deliver on time to customers worldwide.<br \/>\n\t\t\n<style>\n#text-663726236 {\n  color: rgb(40, 49, 50);\n}\n#text-663726236 > * {\n  color: rgb(40, 49, 50);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-538706181\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-why icon-box-left text-left\"  style=\"margin:10px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 46px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/06\/commitment-100x100-1.png\" class=\"attachment-medium size-medium\" alt=\"Commitment 100x100 (1)\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"text-63828692\" class=\"text\">\n\t\t\n<h3>Strict QC<\/h3>\n<p>All input materials, products in process, and finished goods are inspected by our Quality Control (QC) department. Only products that meet the standards are approved for delivery and shipment to customers.<br \/>\n\t\t\n<style>\n#text-63828692 {\n  color: rgb(40, 49, 50);\n}\n#text-63828692 > * {\n  color: rgb(40, 49, 50);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1831873680\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-why icon-box-left text-left\"  style=\"margin:10px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 46px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/06\/performance-100x100-1.png\" class=\"attachment-medium size-medium\" alt=\"Performance 100x100\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"text-2537827977\" class=\"text\">\n\t\t\n<h3>Perfect After-sales Service System<\/h3>\n<p>Our after-sales service aims to make you forget that after-sales service even exists.<br \/>\n\t\t\n<style>\n#text-2537827977 {\n  color: rgb(40, 49, 50);\n}\n#text-2537827977 > * {\n  color: rgb(40, 49, 50);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_921531531 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(237, 248, 255);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_541571581\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\t<div id=\"text-3441859226\" class=\"text\">\n\t\t\n<h2>Our Development Orientation<\/h2>\n\t\t\n<style>\n#text-3441859226 {\n  font-size: 1.5rem;\n  text-align: center;\n  color: #0045b1;\n}\n#text-3441859226 > * {\n  color: #0045b1;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-920784910\" class=\"text\">\n\t\t\n<p>We develop with an orientation that takes quality as the foundation and customers as the center, constantly innovating to provide effective, sustainable, and reliable plastic packaging solutions.<\/p>\n\t\t\n<style>\n#text-920784910 {\n  font-size: 1.1rem;\n  text-align: center;\n  color: #0045b1;\n}\n#text-920784910 > * {\n  color: #0045b1;\n}\n@media (min-width:550px) {\n  #text-920784910 {\n    font-size: 1.25rem;\n  }\n}\n@media (min-width:850px) {\n  #text-920784910 {\n    font-size: 1rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-642412672\">\n\n\t<div id=\"col-1977832637\" class=\"col w-50 medium-6 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/06\/logo-uy-tin-100x100-1.png\" class=\"attachment-medium size-medium\" alt=\"Reputation Logo 100x100\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"text-2126266993\" class=\"text\">\n\t\t\n<p><strong>VISION<\/strong><\/p>\n\t\t\n<style>\n#text-2126266993 {\n  font-size: 1rem;\n  color: #012057;\n}\n#text-2126266993 > * {\n  color: #012057;\n}\n@media (min-width:550px) {\n  #text-2126266993 {\n    font-size: 1.5rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2495846031\" class=\"text\">\n\t\t\n<p>We aim to become one of the leading reputable HDPE plastic bottle manufacturers in Vietnam and the region, constantly innovating technology and improving quality to meet the increasingly diverse needs of the market.<\/p>\n\t\t\n<style>\n#text-2495846031 {\n  font-size: 1.1rem;\n  color: rgb(0,0,0);\n}\n#text-2495846031 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-862474591\" class=\"col w-50 medium-6 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/06\/logo-tham-my-100x100-1.png\" class=\"attachment-medium size-medium\" alt=\"Aesthetics Logo 100x100\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"text-347868955\" class=\"text\">\n\t\t\n<p><strong>MISSION<\/strong><\/p>\n\t\t\n<style>\n#text-347868955 {\n  font-size: 1rem;\n  color: #012057;\n}\n#text-347868955 > * {\n  color: #012057;\n}\n@media (min-width:550px) {\n  #text-347868955 {\n    font-size: 1.5rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3544986386\" class=\"text\">\n\t\t\n<p>To provide safe, sustainable, and cost-optimized plastic packaging solutions for customers; while contributing to enhancing product value and supporting the long-term development of our partners.<\/p>\n\t\t\n<style>\n#text-3544986386 {\n  font-size: 1.1rem;\n  color: rgb(0,0,0);\n}\n#text-3544986386 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1025507171\" class=\"col w-50 medium-6 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/06\/logo-gia-ca-100x100-1.png\" class=\"attachment-medium size-medium\" alt=\"Pricing Logo 100x100\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"text-1666151795\" class=\"text\">\n\t\t\n<p><strong>CORE VALUES<\/strong><\/p>\n\t\t\n<style>\n#text-1666151795 {\n  font-size: 1rem;\n  color: #012057;\n}\n#text-1666151795 > * {\n  color: #012057;\n}\n@media (min-width:550px) {\n  #text-1666151795 {\n    font-size: 1.5rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3605044581\" class=\"text\">\n\t\t\n<p>Taking quality as the foundation, prestige as the commitment, customers as the center, and constantly improving for sustainable development. We uphold the spirit of responsibility, cooperation, and creativity in all production and business activities. <\/p>\n\t\t\n<style>\n#text-3605044581 {\n  font-size: 1.1rem;\n  color: rgb(0,0,0);\n}\n#text-3605044581 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_541571581 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section hide-for-medium\" id=\"section_1107682529\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\t<div id=\"text-2198823336\" class=\"text\">\n\t\t\n<h2>Actual Images<\/h2>\n\t\t\n<style>\n#text-2198823336 {\n  font-size: 1.2rem;\n  text-align: center;\n  color: #0045b1;\n}\n#text-2198823336 > * {\n  color: #0045b1;\n}\n@media (min-width:550px) {\n  #text-2198823336 {\n    font-size: 1.15rem;\n  }\n}\n@media (min-width:850px) {\n  #text-2198823336 {\n    font-size: 1.5rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-1598553674\">\n\n\t<div id=\"col-1909929610\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-2 row-xsmall row-full-width\" >\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10008.jpg\" title=\"10008\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-cover\" style=\"padding-top:75%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10008-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"10008\" ids=\"2256,2257,2258,2259,2260,2261,2262,2263\" style=\"none\" lightbox_image_size=\"original\" col_spacing=\"xsmall\" image_height=\"75%\" srcset=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10008-400x400.jpg 400w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10008-600x600.jpg 600w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10008-100x100.jpg 100w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10008-280x280.jpg 280w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10008-768x768.jpg 768w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10008.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>10008<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10007.jpg\" title=\"10007\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-cover\" style=\"padding-top:75%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10007-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"10007\" ids=\"2256,2257,2258,2259,2260,2261,2262,2263\" style=\"none\" lightbox_image_size=\"original\" col_spacing=\"xsmall\" image_height=\"75%\" srcset=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10007-400x400.jpg 400w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10007-600x600.jpg 600w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10007-100x100.jpg 100w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10007-800x800.jpg 800w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10007-280x280.jpg 280w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10007-768x768.jpg 768w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10007.jpg 1500w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>10007<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10004.jpg\" title=\"10004\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-cover\" style=\"padding-top:75%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10004-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"10004\" ids=\"2256,2257,2258,2259,2260,2261,2262,2263\" style=\"none\" lightbox_image_size=\"original\" col_spacing=\"xsmall\" image_height=\"75%\" srcset=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10004-400x400.jpg 400w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10004-600x600.jpg 600w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10004-100x100.jpg 100w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10004-280x280.jpg 280w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10004-768x768.jpg 768w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10004.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>10004<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10009.jpg\" title=\"10009\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-cover\" style=\"padding-top:75%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10009-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"10009\" ids=\"2256,2257,2258,2259,2260,2261,2262,2263\" style=\"none\" lightbox_image_size=\"original\" col_spacing=\"xsmall\" image_height=\"75%\" srcset=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10009-400x400.jpg 400w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10009-600x600.jpg 600w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10009-100x100.jpg 100w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10009-280x280.jpg 280w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10009-768x768.jpg 768w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10009.jpg 797w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>10009<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10005.jpg\" title=\"10005\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-cover\" style=\"padding-top:75%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10005-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"10005\" ids=\"2256,2257,2258,2259,2260,2261,2262,2263\" style=\"none\" lightbox_image_size=\"original\" col_spacing=\"xsmall\" image_height=\"75%\" srcset=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10005-400x400.jpg 400w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10005-600x600.jpg 600w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10005-100x100.jpg 100w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10005-280x280.jpg 280w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10005-768x768.jpg 768w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10005.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>10005<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10027.jpg\" title=\"10027\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-cover\" style=\"padding-top:75%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10027-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"10027\" ids=\"2256,2257,2258,2259,2260,2261,2262,2263\" style=\"none\" lightbox_image_size=\"original\" col_spacing=\"xsmall\" image_height=\"75%\" srcset=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10027-400x400.jpg 400w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10027-600x600.jpg 600w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10027-100x100.jpg 100w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10027-280x280.jpg 280w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10027-768x768.jpg 768w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10027.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>10027<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10018.jpg\" title=\"10018\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-cover\" style=\"padding-top:75%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10018-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"10018\" ids=\"2256,2257,2258,2259,2260,2261,2262,2263\" style=\"none\" lightbox_image_size=\"original\" col_spacing=\"xsmall\" image_height=\"75%\" srcset=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10018-400x400.jpg 400w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10018-600x600.jpg 600w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10018-100x100.jpg 100w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10018-280x280.jpg 280w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10018-768x768.jpg 768w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10018.jpg 793w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>10018<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10020.jpg\" title=\"10020\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-cover\" style=\"padding-top:75%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10020-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"10020\" ids=\"2256,2257,2258,2259,2260,2261,2262,2263\" style=\"none\" lightbox_image_size=\"original\" col_spacing=\"xsmall\" image_height=\"75%\" srcset=\"https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10020-400x400.jpg 400w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10020-600x600.jpg 600w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10020-100x100.jpg 100w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10020-280x280.jpg 280w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10020-768x768.jpg 768w, https:\/\/www.fleidvn.com\/wp-content\/uploads\/2026\/04\/10020.jpg 794w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>10020<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1107682529 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n@media (min-width:550px) {\n  #section_1107682529 {\n    padding-top: 0px;\n    padding-bottom: 0px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section show-for-medium\" id=\"section_1861126815\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\t<div id=\"text-2383666202\" class=\"text\">\n\t\t\n<h2>Actual Images<\/h2>\n\t\t\n<style>\n#text-2383666202 {\n  font-size: 1.2rem;\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-2383666202 > * {\n  color: rgb(0,0,0);\n}\n@media (min-width:550px) {\n  #text-2383666202 {\n    font-size: 1.15rem;\n  }\n}\n@media (min-width:850px) {\n  #text-2383666202 {\n    font-size: 1.6rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-9512935\">\n\n\t<div id=\"col-1058109666\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"slider-wrapper relative\" id=\"slider-978030827\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 6000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": false,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_537990665\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_537990665 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_971156667\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_971156667 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1727259920\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1727259920 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_896699981\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_896699981 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_645267959\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_645267959 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1837259643\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1837259643 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1049103506\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1049103506 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_693137877\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_693137877 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_845569778\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_845569778 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_253015763\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_253015763 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_319851141\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_319851141 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1861126815 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n@media (min-width:550px) {\n  #section_1861126815 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1779598178\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\t<div id=\"text-3824328029\" class=\"text\">\n\t\t\n<h2>Contact for Cooperation<\/h2>\n\t\t\n<style>\n#text-3824328029 {\n  font-size: 1.5rem;\n  text-align: center;\n  color: rgb(0, 69, 177);\n}\n#text-3824328029 > * {\n  color: rgb(0, 69, 177);\n}\n@media (min-width:550px) {\n  #text-3824328029 {\n    font-size: 1.15rem;\n  }\n}\n@media (min-width:850px) {\n  #text-3824328029 {\n    font-size: 1.6rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-1371212312\">\n\n\t<div id=\"col-1059752939\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3864902340\" class=\"text\">\n\t\t\n<p>We always welcome partners, businesses, and customers to visit and experience our <strong>professional HDPE plastic<\/strong> bottle production process with stable quality, dedicated service, and optimal solutions.<\/p>\n\t\t\n<style>\n#text-3864902340 {\n  font-size: 1.1rem;\n  color: rgb(0,0,0);\n}\n#text-3864902340 > * {\n  color: rgb(0,0,0);\n}\n@media (min-width:550px) {\n  #text-3864902340 {\n    font-size: 1.3rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1059752939 > .col-inner {\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1583524243\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"tel:0987473389\" class=\"button primary is-shade box-shadow-4 box-shadow-5-hover\"  style=\"border-radius:10px;\">\n\t\t<span>Contact Now<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1779598178 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n@media (min-width:550px) {\n  #section_1779598178 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2265","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.fleidvn.com\/en\/wp-json\/wp\/v2\/pages\/2265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fleidvn.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fleidvn.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fleidvn.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fleidvn.com\/en\/wp-json\/wp\/v2\/comments?post=2265"}],"version-history":[{"count":3,"href":"https:\/\/www.fleidvn.com\/en\/wp-json\/wp\/v2\/pages\/2265\/revisions"}],"predecessor-version":[{"id":2268,"href":"https:\/\/www.fleidvn.com\/en\/wp-json\/wp\/v2\/pages\/2265\/revisions\/2268"}],"wp:attachment":[{"href":"https:\/\/www.fleidvn.com\/en\/wp-json\/wp\/v2\/media?parent=2265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}